{"id":392,"count":6,"description":"Intellectual of the Arab world in the 18th and 19th century","link":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/","name":"The Arab Renaissance","slug":"the-arab-renaissance","taxonomy":"category","parent":58,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627\" \/>\n<meta property=\"og:description\" content=\"Intellectual of the Arab world in the 18th and 19th century\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/\" \/>\n<meta property=\"og:site_name\" content=\"\u062d\u0650\u0646\u0651\u0627\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hennaplatform\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/en\\\/category\\\/issues\\\/the-arab-renaissance\\\/\",\"url\":\"https:\\\/\\\/hennaplatform.com\\\/en\\\/category\\\/issues\\\/the-arab-renaissance\\\/\",\"name\":\"The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/en\\\/category\\\/issues\\\/the-arab-renaissance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/en\\\/category\\\/issues\\\/the-arab-renaissance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hennaplatform.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Issues\",\"item\":\"https:\\\/\\\/hennaplatform.com\\\/en\\\/category\\\/middle-east\\\/issues\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Arab Renaissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#website\",\"url\":\"https:\\\/\\\/hennaplatform.com\\\/\",\"name\":\"\u062d\u0650\u0646\u0651\u0627\",\"description\":\"Henna Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hennaplatform.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#organization\",\"name\":\"Henna Platform - \u062d\u0650\u0646\u0651\u0627\",\"url\":\"https:\\\/\\\/hennaplatform.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/hennaplatform.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-Logo.jpeg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/hennaplatform.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-Logo.jpeg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Henna Platform - \u062d\u0650\u0646\u0651\u0627\"},\"image\":{\"@id\":\"https:\\\/\\\/hennaplatform.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HennaPlatform\\\/\",\"https:\\\/\\\/x.com\\\/hennaplatform\",\"https:\\\/\\\/www.instagram.com\\\/hennaplatform\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/","og_locale":"en_US","og_type":"article","og_title":"The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627","og_description":"Intellectual of the Arab world in the 18th and 19th century","og_url":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/","og_site_name":"\u062d\u0650\u0646\u0651\u0627","twitter_card":"summary_large_image","twitter_site":"@hennaplatform","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/","url":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/","name":"The Arab Renaissance Archives - \u062d\u0650\u0646\u0651\u0627","isPartOf":{"@id":"https:\/\/hennaplatform.com\/#website"},"breadcrumb":{"@id":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hennaplatform.com\/en\/category\/issues\/the-arab-renaissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hennaplatform.com\/"},{"@type":"ListItem","position":2,"name":"Issues","item":"https:\/\/hennaplatform.com\/en\/category\/middle-east\/issues\/"},{"@type":"ListItem","position":3,"name":"The Arab Renaissance"}]},{"@type":"WebSite","@id":"https:\/\/hennaplatform.com\/#website","url":"https:\/\/hennaplatform.com\/","name":"\u062d\u0650\u0646\u0651\u0627","description":"Henna Platform","publisher":{"@id":"https:\/\/hennaplatform.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hennaplatform.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hennaplatform.com\/#organization","name":"Henna Platform - \u062d\u0650\u0646\u0651\u0627","url":"https:\/\/hennaplatform.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hennaplatform.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/hennaplatform.com\/wp-content\/uploads\/2021\/04\/cropped-Logo.jpeg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/hennaplatform.com\/wp-content\/uploads\/2021\/04\/cropped-Logo.jpeg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Henna Platform - \u062d\u0650\u0646\u0651\u0627"},"image":{"@id":"https:\/\/hennaplatform.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HennaPlatform\/","https:\/\/x.com\/hennaplatform","https:\/\/www.instagram.com\/hennaplatform\/"]}]}},"_links":{"self":[{"href":"https:\/\/hennaplatform.com\/en\/wp-json\/wp\/v2\/categories\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hennaplatform.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hennaplatform.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/hennaplatform.com\/en\/wp-json\/wp\/v2\/categories\/58"}],"wp:post_type":[{"href":"https:\/\/hennaplatform.com\/en\/wp-json\/wp\/v2\/posts?categories=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}